{"id":772,"date":"2006-04-25T07:00:00","date_gmt":"2006-04-25T05:00:00","guid":{"rendered":"http:\/\/www.nsonic.de\/blog\/2006\/04\/nsonic-57-denk-mal-einzelhandel-wohin-gehst-du\/"},"modified":"2020-10-03T13:36:38","modified_gmt":"2020-10-03T11:36:38","slug":"nsonic-57-denk-mal-einzelhandel-wohin-gehst-du","status":"publish","type":"post","link":"https:\/\/www.nsonic.de\/blog\/2006\/04\/nsonic-57-denk-mal-einzelhandel-wohin-gehst-du\/","title":{"rendered":"nSonic #57 &#8211; Denk Mal &#8211; Einzelhandel, wohin gehst Du?"},"content":{"rendered":"<p><img src=\"http:\/\/www.nsonic-net.de\/podcast\/img\/057_denkmal_einzelhandel.jpg\" alt=\"Denk Mal - Einzelhandel\" \/><br \/>\nMein lieber Einzelhandel: Warum entwickelst Du nicht ein klein wenig Fantasie um Deinen Kunden eine echte Alternative zum Onlinehandel zu bieten?<br \/>\nIch kenne Viele, die bereit sind etwas mehr Geld beim lokalen H\u00e4ndler zu lassen (anstatt im Internet zu bestellen) &#8211; wenn die H\u00e4ndler nat\u00fcrlich nicht in der Lage sind dem Kunden ein Produkt auch zu besorgen&#8230; ja, dann wei\u00df ich auch nicht mehr wie ich helfen soll &#8230;.<\/p>\n<p>Wie sind Eure Erfahrungen mit dem Einzelhandel? Eher positiv oder eher negativ? Schreibt mir in die Kommentarfunktion.<\/p>\n<p><a href=\"http:\/\/www.podtrac.com\/pts\/redirect.mp3?http:\/\/nsonic.podplace.de\/nsonic_57_denkmal_einzelhandel.mp3\">Folge herunterladen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mein lieber Einzelhandel: Warum entwickelst Du nicht ein klein wenig Fantasie um Deinen Kunden eine echte Alternative zum Onlinehandel zu bieten? Ich kenne&hellip;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[51],"tags":[846,592],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p71Tml-cs","_links":{"self":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts\/772"}],"collection":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/comments?post=772"}],"version-history":[{"count":3,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts\/772\/revisions"}],"predecessor-version":[{"id":7194,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts\/772\/revisions\/7194"}],"wp:attachment":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/media?parent=772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/categories?post=772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/tags?post=772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}