{"id":1327,"date":"2008-09-06T23:50:46","date_gmt":"2008-09-06T22:50:46","guid":{"rendered":"http:\/\/www.nsonic.de\/blog\/2008\/09\/nsonic-168-mac-nachschlag\/"},"modified":"2013-01-06T13:22:49","modified_gmt":"2013-01-06T12:22:49","slug":"nsonic-168-mac-nachschlag","status":"publish","type":"post","link":"https:\/\/www.nsonic.de\/blog\/2008\/09\/nsonic-168-mac-nachschlag\/","title":{"rendered":"nSonic #168 &#8211; Mac &#8211; Nachschlag"},"content":{"rendered":"<p><img src=\"https:\/\/www.nsonic.de\/blog\/wp-content\/uploads\/2008\/09\/168_mac_nachschlag.jpg\" alt=\"Podcast Mac Nachschlag\" \/><br \/>\nEs haben sich einige Kommentare und Erg\u00e4nzungen von Euch angesammelt. Einige davon betreffen die Mac-Folgen.<br \/>\nGrund genug f\u00fcr einen R\u00fcckblick auf die Folgen <a href=\"https:\/\/www.nsonic.de\/blog\/2008\/06\/nsonic-158-mac-screenshot-von-dvd\/\">#158<\/a> und <a href=\"https:\/\/www.nsonic.de\/blog\/2008\/08\/nsonic-164-mac-making-of\/\">#164<\/a>.<br \/>\nIn dieser Folge erfahrt Ihr nun, welches Bildformat eigentlich Standard f\u00fcr die Bildschirmfotos ist und wie man dieses Format einfach \u00e4ndern kann. Au\u00dferdem landen Bildschirmfotos, die man aus dem Terminal heraus mit screencapture anfertigt, nicht automatisch im Benutzerverzeichnis. Wo sie landen und wie man das sehr einfach per Drag&amp;Drop beeinflussen kann ist ebenfalls ein Thema. Au\u00dferdem gibt es noch einen Tipp f\u00fcr den Bildschirm-Zoom.<\/p>\n<p><a href=\"http:\/\/www.podtrac.com\/pts\/redirect.m4v\/nsonic.podplace.de\/nsonic_168_mac_nachschlag.m4v\">Folge herunterladen<\/a><\/p>\n<p>[flashvideo video=http:\/\/www.podtrac.com\/pts\/redirect.m4v\/nsonic.podplace.de\/nsonic_168_mac_nachschlag.m4v preview=http:\/\/nsonic.podplace.de\/nsonic_168.jpg \/]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da ich nun immer h\u00e4ufiger gefragt werde mit welcher Software ich diese Mac-Video-Folgen aufnehme, gibt es hier mal eine kleine Erkl\u00e4rung dazu.<br \/>\nInsgesamt kommen folgende Programme zum Einsatz:<\/p>\n<ul>\n<li><a target=\"_blank\" href=\"http:\/\/www.apple.com\/de\/iwork\/keynote\/\">Keynote<\/a> &#8211; f\u00fcr das Intro und Outro.<\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.araelium.com\/screenflick\/\">Screenflick<\/a> &#8211; zum aufzeichnen der Bildschirmsitzungen<\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.boinx.com\/mousepose\/overview\/\">Mousepos\u00e9<\/a> &#8211; zum hervorheben des Mauszeigers<\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.apple.com\/de\/macosx\/\">OS-X<\/a> 10.4 &#8211; zum Zoomen des Bildschirms <span class=\"wp-smiley emoji emoji-smile\" title=\":)\">:)<\/span>  Im Making Of zeige ich wie es geht<\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.apple.com\/support\/downloads\/imovieHD6.html\">iMovie HD<\/a> &#8211; um die Videos aus Keynote und Screenflick zusammen zu schneiden. Gibt es inzwischen kostenlos von Apple (f\u00fcr Besitzer von iLive &#8217;08) da iMovie &#8217;06 ausgemustert und durch iMovie &#8217;08 ersetzt wurde die allerdings komplett anders funktioniert<\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.apple.com\/de\/ilife\/garageband\/\">GarageBand<\/a> &#8211; Intro-\/Outro-Musik, Filter\/Kompressor f\u00fcr Sprachspur<\/li>\n<li><a target=\"_blank\" href=\"http:\/\/www.apple.com\/de\/itunes\/\">iTunes<\/a> &#8211; wandelt das Video ins iPod-Format<\/li>\n<\/ul>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":""},"categories":[55,51],"tags":[477,839,133,480,481],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p71Tml-lp","_links":{"self":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts\/1327"}],"collection":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":4,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts\/1327\/revisions"}],"predecessor-version":[{"id":4842,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/posts\/1327\/revisions\/4842"}],"wp:attachment":[{"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/media?parent=1327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/categories?post=1327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nsonic.de\/blog\/wp-json\/wp\/v2\/tags?post=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}